{"id":1,"name":"harapanbesartobasa.com","url":"http:\/\/harapanbesartobasa.com","description":"","link":"https:\/\/harapanbesartobasa.com\/index.php\/author\/harapanbesartobasa-com\/","slug":"harapanbesartobasa-com","avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/8d402a15450490283ca8d78f3a235de7?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/8d402a15450490283ca8d78f3a235de7?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/8d402a15450490283ca8d78f3a235de7?s=96&d=mm&r=g"},"meta":[],"_links":{"self":[{"href":"https:\/\/harapanbesartobasa.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"collection":[{"href":"https:\/\/harapanbesartobasa.com\/index.php\/wp-json\/wp\/v2\/users"}]}}